{"id":3109,"date":"2017-09-19T03:06:18","date_gmt":"2017-09-19T03:06:18","guid":{"rendered":"https:\/\/fabricadigital.com.mx\/membresia\/my-account-2\/"},"modified":"2017-09-19T03:06:18","modified_gmt":"2017-09-19T03:06:18","slug":"my-account-2","status":"publish","type":"page","link":"https:\/\/fabricadigital.com.mx\/membresia\/my-account-2\/","title":{"rendered":"My account"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/pages\/3109"}],"collection":[{"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/comments?post=3109"}],"version-history":[{"count":0,"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/pages\/3109\/revisions"}],"wp:attachment":[{"href":"https:\/\/fabricadigital.com.mx\/membresia\/wp-json\/wp\/v2\/media?parent=3109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}